{"id":54541,"date":"2026-07-14T19:28:59","date_gmt":"2026-07-15T01:28:59","guid":{"rendered":"https:\/\/reporterosdelsur.org\/diario\/?p=54541"},"modified":"2026-07-14T21:27:07","modified_gmt":"2026-07-15T03:27:07","slug":"credito-ganadero-a-la-palabra-devuelve-esperanza-a-pequenos-productores-de-tabasco","status":"publish","type":"post","link":"https:\/\/reporterosdelsur.org\/diario\/2026\/07\/credito-ganadero-a-la-palabra-devuelve-esperanza-a-pequenos-productores-de-tabasco\/","title":{"rendered":"Cr\u00e9dito Ganadero a la Palabra devuelve esperanza a peque\u00f1os productores de Tabasco&#8230;"},"content":{"rendered":"\n<p><strong>Jalpa de M\u00e9ndez, Tabasco.<\/strong> Lo que durante a\u00f1os fue una lucha constante para cientos de peque\u00f1os ganaderos de Tabasco comienza a transformarse con el programa <strong>Cr\u00e9dito Ganadero a la Palabra<\/strong>, una estrategia impulsada por el Gobierno del Pueblo que busca reconstruir el patrimonio de las familias dedicadas a la actividad pecuaria y fortalecer la econom\u00eda del campo.<\/p>\n\n\n\n<p>Durante d\u00e9cadas, productores con hatos reducidos y escaso acceso a apoyos institucionales enfrentaron dificultades para mantener y hacer crecer sus unidades de producci\u00f3n. Hoy, con la entrega de vientres y sementales, esa realidad empieza a cambiar para quienes, por a\u00f1os, permanecieron al margen de los programas gubernamentales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-1024x683.jpeg\" alt=\"\" class=\"wp-image-54543\" srcset=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-1024x683.jpeg 1024w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-300x200.jpeg 300w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-768x512.jpeg 768w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-1200x800.jpeg 1200w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-465x310.jpeg 465w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2-695x464.jpeg 695w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Uno de ellos es el m\u00e9dico veterinario <strong>Adolfo Caraveo Madrigal<\/strong>, originario de la rancher\u00eda El R\u00edo, en Jalpa de M\u00e9ndez, quien tras 55 a\u00f1os dedicado a la ganader\u00eda asegur\u00f3 que nunca hab\u00eda presenciado un programa de esta magnitud enfocado en los peque\u00f1os productores.<\/p>\n\n\n\n<p>El beneficiario se\u00f1al\u00f3 que recibir un paquete integrado por 10 vientres y un semental representa una oportunidad para fortalecer su patrimonio, incrementar la producci\u00f3n de leche destinada al autoconsumo y hacer crecer paulatinamente su hato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-1024x683.jpeg\" alt=\"\" class=\"wp-image-54556\" srcset=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-1024x683.jpeg 1024w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-300x200.jpeg 300w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-768x512.jpeg 768w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-1200x800.jpeg 1200w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-465x310.jpeg 465w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E-695x464.jpeg 695w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/HNN-5aPWUAAr93E.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&#8220;En el pasado est\u00e1bamos al garete; los apoyos no bajaban y, cuando llegaban, eran para quienes estaban m\u00e1s relacionados con el gobierno&#8221;, expres\u00f3 al recordar las dificultades que enfrentaban los productores para acceder a este tipo de beneficios.<\/p>\n\n\n\n<p>La experiencia tambi\u00e9n es compartida por <strong>Elsy Yadira Garc\u00eda V\u00e1zquez<\/strong>, de la rancher\u00eda Huapacal primera secci\u00f3n, quien despu\u00e9s de tres d\u00e9cadas dedicada a la ganader\u00eda recibi\u00f3 por primera vez un apoyo gubernamental para fortalecer su actividad productiva.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-1024x683.jpeg\" alt=\"\" class=\"wp-image-54558\" srcset=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-1024x683.jpeg 1024w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-300x200.jpeg 300w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-768x512.jpeg 768w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-1536x1024.jpeg 1536w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-2048x1365.jpeg 2048w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-1200x800.jpeg 1200w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-465x310.jpeg 465w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/vaca-1-695x463.jpeg 695w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La productora afirm\u00f3 que el paquete ganadero representa un impulso para su familia y una oportunidad para incrementar sus ingresos, al tiempo que permitir\u00e1 consolidar una actividad que ha sido el sustento de su hogar durante m\u00e1s de 30 a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-1024x683.jpeg\" alt=\"\" class=\"wp-image-54544\" srcset=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-1024x683.jpeg 1024w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-300x200.jpeg 300w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-768x512.jpeg 768w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-465x310.jpeg 465w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3-695x464.jpeg 695w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-3.jpeg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>&#8220;En 30 a\u00f1os nunca hab\u00eda recibido un apoyo del gobierno&#8221;, manifest\u00f3 con satisfacci\u00f3n, al considerar que este programa abre nuevas oportunidades para que los peque\u00f1os ganaderos puedan desarrollar su actividad en mejores condiciones.<\/p>\n\n\n\n<p>El programa <strong>Cr\u00e9dito Ganadero a la Palabra<\/strong>, impulsado por el gobernador <strong>Javier May Rodr\u00edguez<\/strong>, es una iniciativa \u00fanica en el pa\u00eds que tiene como prop\u00f3sito repoblar el hato ganadero estatal mediante la entrega directa de ganado a las y los productores, sin intermediarios y bajo un esquema de confianza.<\/p>\n\n\n\n<p>Adem\u00e1s de fortalecer la producci\u00f3n pecuaria, la estrategia busca reconstruir el patrimonio de las familias rurales, dinamizar la econom\u00eda de las comunidades y garantizar que las nuevas generaciones encuentren en el campo una alternativa viable para su desarrollo y bienestar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jalpa de M\u00e9ndez, Tabasco. Lo que durante a\u00f1os fue una lucha constante para cientos de peque\u00f1os ganaderos de Tabasco comienza a transformarse con el programa Cr\u00e9dito Ganadero a la Palabra, una estrategia impulsada por el Gobierno del Pueblo que busca reconstruir el patrimonio de las familias dedicadas a la actividad<span class=\"more-link theme-more-link\"><a href=\"https:\/\/reporterosdelsur.org\/diario\/2026\/07\/credito-ganadero-a-la-palabra-devuelve-esperanza-a-pequenos-productores-de-tabasco\/\">Leer Nota Complete<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":54542,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,2],"tags":[736,1844,379,418,177,38,348,640,1845,1843,381,333,563],"class_list":["entry","author-admin","post-54541","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-tabasco","tag-audiencia-publica","tag-creditos-a-la-palabra","tag-ganaderia","tag-gobierno-de-tabasco","tag-javier-may-rodriguez","tag-noticias","tag-obras-publicas","tag-obras-sociales","tag-porcinos","tag-sector-primario","tag-sedap","tag-seguridad","tag-sembrando-vida"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1.jpeg",1280,720,false],"thumbnail":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-150x150.jpeg",150,150,true],"medium":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-300x169.jpeg",300,169,true],"medium_large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-768x432.jpeg",768,432,true],"large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-1024x576.jpeg",1024,576,true],"1536x1536":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1.jpeg",1280,720,false],"2048x2048":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1.jpeg",1280,720,false],"ultp_layout_landscape_large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-1200x720.jpeg",1200,720,true],"ultp_layout_landscape":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-870x570.jpeg",870,570,true],"ultp_layout_portrait":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-600x720.jpeg",600,720,true],"ultp_layout_square":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-600x600.jpeg",600,600,true],"hoot-medium-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-460x400.jpeg",460,400,true],"hoot-preview":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-465x262.jpeg",465,262,true],"hoot-preview-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-465x550.jpeg",465,550,true],"hoot-large-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-690x550.jpeg",690,550,true],"hoot-preview-large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-695x391.jpeg",695,391,true],"hoot-wide-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-920x425.jpeg",920,425,true],"hoot-extra-wide-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Ganada-1-1035x425.jpeg",1035,425,true]},"author_info":{"display_name":"Reporteros del Sur","author_link":"https:\/\/reporterosdelsur.org\/diario\/author\/admin\/"},"category_info":"<a href=\"https:\/\/reporterosdelsur.org\/diario\/category\/destacado\/\" rel=\"category tag\">Destacado<\/a> <a href=\"https:\/\/reporterosdelsur.org\/diario\/category\/tabasco\/\" rel=\"category tag\">Tabasco<\/a>","tag_info":"Tabasco","comment_count":"0","_links":{"self":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/comments?post=54541"}],"version-history":[{"count":2,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54541\/revisions"}],"predecessor-version":[{"id":54559,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54541\/revisions\/54559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/media\/54542"}],"wp:attachment":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/media?parent=54541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/categories?post=54541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/tags?post=54541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}