{"id":54524,"date":"2026-07-14T19:59:21","date_gmt":"2026-07-15T01:59:21","guid":{"rendered":"https:\/\/reporterosdelsur.org\/diario\/?p=54524"},"modified":"2026-07-14T21:27:48","modified_gmt":"2026-07-15T03:27:48","slug":"tabasco-mantiene-tendencia-a-la-baja-en-delitos-de-alto-impacto-disminuye-el-homicidio-doloso","status":"publish","type":"post","link":"https:\/\/reporterosdelsur.org\/diario\/2026\/07\/tabasco-mantiene-tendencia-a-la-baja-en-delitos-de-alto-impacto-disminuye-el-homicidio-doloso\/","title":{"rendered":"Tabasco mantiene tendencia a la baja en delitos de alto impacto; disminuye el homicidio doloso"},"content":{"rendered":"\n<p><strong>TABASCO.-<\/strong> Como resultado del trabajo coordinado entre las corporaciones de seguridad de los tres \u00f3rdenes de gobierno, Tabasco mantiene una tendencia a la baja en la incidencia de delitos de alto impacto, destacando la reducci\u00f3n en los casos de homicidio doloso, en el marco de la estrategia nacional de seguridad.<\/p>\n\n\n\n<p>De acuerdo con datos del Secretariado Ejecutivo del Sistema Nacional de Seguridad P\u00fablica (SESNSP), durante el primer semestre de 2026 el promedio diario de homicidios dolosos en M\u00e9xico disminuy\u00f3 37 por ciento en comparaci\u00f3n con el mismo periodo de 2025, reflejando los avances de las acciones implementadas para fortalecer la seguridad y la construcci\u00f3n de la paz.<\/p>\n\n\n\n<p>El organismo tambi\u00e9n inform\u00f3 que, al comparar el promedio diario de homicidios dolosos registrados en junio de cada a\u00f1o, el correspondiente a junio de 2026 representa el nivel m\u00e1s bajo desde 2015. Asimismo, el primer semestre de este a\u00f1o se ubic\u00f3 como el de menor incidencia desde 2016, con un promedio nacional de 49.7 homicidios dolosos diarios.<\/p>\n\n\n\n<p>Durante la conferencia matutina en Palacio Nacional, la presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, destac\u00f3 que, a un a\u00f1o y nueve meses del inicio de su administraci\u00f3n, el promedio diario de homicidios dolosos en el pa\u00eds se redujo 48 por ciento, al pasar de 86.9 casos diarios en septiembre de 2024 a 45.4 en junio de 2026.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"380\" src=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-2.jpeg\" alt=\"\" class=\"wp-image-54526\" srcset=\"https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-2.jpeg 650w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-2-300x175.jpeg 300w, https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-2-465x272.jpeg 465w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/figure>\n\n\n\n<p>La mandataria federal subray\u00f3 que estos resultados son consecuencia de la estrategia integral de seguridad que impulsa el Gobierno de M\u00e9xico a trav\u00e9s del Gabinete de Seguridad, con acciones enfocadas en la construcci\u00f3n de la paz, el fortalecimiento de la justicia y la atenci\u00f3n a las causas que generan la violencia.<\/p>\n\n\n\n<p>&#8220;Es una estrategia que est\u00e1 dando resultados&#8221;, afirm\u00f3 Sheinbaum Pardo, al reiterar que el objetivo de su administraci\u00f3n es continuar disminuyendo los delitos de alto impacto y consolidar un entorno de mayor seguridad para la poblaci\u00f3n.<\/p>\n\n\n\n<p>En este contexto, Tabasco se mantiene alineado a la estrategia nacional mediante la coordinaci\u00f3n permanente entre autoridades federales, estatales y municipales, lo que ha permitido fortalecer las acciones de prevenci\u00f3n, inteligencia y combate a la delincuencia, contribuyendo a la disminuci\u00f3n de los delitos de mayor impacto en la entidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TABASCO.- Como resultado del trabajo coordinado entre las corporaciones de seguridad de los tres \u00f3rdenes de gobierno, Tabasco mantiene una tendencia a la baja en la incidencia de delitos de alto impacto, destacando la reducci\u00f3n en los casos de homicidio doloso, en el marco de la estrategia nacional de seguridad.<span class=\"more-link theme-more-link\"><a href=\"https:\/\/reporterosdelsur.org\/diario\/2026\/07\/tabasco-mantiene-tendencia-a-la-baja-en-delitos-de-alto-impacto-disminuye-el-homicidio-doloso\/\">Leer Nota Complete<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":54525,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,2],"tags":[694,982,371,1355,491,38,372,132,459,333,34],"class_list":["entry","author-admin","post-54524","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-tabasco","tag-extorsion","tag-fgr-tabasco","tag-gn","tag-llamadas-telefonicas","tag-marina","tag-noticias","tag-operativos","tag-secuestro","tag-sedena","tag-seguridad","tag-villahermosa"],"jetpack_publicize_connections":[],"featured_image_urls":{"full":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1.jpeg",1599,899,false],"thumbnail":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-150x150.jpeg",150,150,true],"medium":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-300x169.jpeg",300,169,true],"medium_large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-768x432.jpeg",768,432,true],"large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-1024x576.jpeg",1024,576,true],"1536x1536":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-1536x864.jpeg",1536,864,true],"2048x2048":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1.jpeg",1599,899,false],"ultp_layout_landscape_large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-1200x800.jpeg",1200,800,true],"ultp_layout_landscape":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-870x570.jpeg",870,570,true],"ultp_layout_portrait":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-600x899.jpeg",600,899,true],"ultp_layout_square":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-600x600.jpeg",600,600,true],"hoot-medium-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-460x400.jpeg",460,400,true],"hoot-preview":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-465x261.jpeg",465,261,true],"hoot-preview-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-465x550.jpeg",465,550,true],"hoot-large-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-690x550.jpeg",690,550,true],"hoot-preview-large":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-695x391.jpeg",695,391,true],"hoot-wide-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-920x425.jpeg",920,425,true],"hoot-extra-wide-thumb":["https:\/\/reporterosdelsur.org\/diario\/wp-content\/uploads\/2026\/07\/Seg-1-1035x425.jpeg",1035,425,true]},"author_info":{"display_name":"Reporteros del Sur","author_link":"https:\/\/reporterosdelsur.org\/diario\/author\/admin\/"},"category_info":"<a href=\"https:\/\/reporterosdelsur.org\/diario\/category\/destacado\/\" rel=\"category tag\">Destacado<\/a> <a href=\"https:\/\/reporterosdelsur.org\/diario\/category\/tabasco\/\" rel=\"category tag\">Tabasco<\/a>","tag_info":"Tabasco","comment_count":"0","_links":{"self":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/comments?post=54524"}],"version-history":[{"count":1,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54524\/revisions"}],"predecessor-version":[{"id":54527,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/posts\/54524\/revisions\/54527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/media\/54525"}],"wp:attachment":[{"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/media?parent=54524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/categories?post=54524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reporterosdelsur.org\/diario\/wp-json\/wp\/v2\/tags?post=54524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}